{"id":12178,"date":"2023-04-12T02:09:44","date_gmt":"2023-04-12T02:09:44","guid":{"rendered":"https:\/\/nxcompressor.com\/?p=12178"},"modified":"2026-02-11T19:03:32","modified_gmt":"2026-02-11T11:03:32","slug":"how-to-set-up-an-air-compressor-a-step-by-step-guide","status":"publish","type":"post","link":"https:\/\/nxcompressor.com\/es\/how-to-set-up-an-air-compressor-a-step-by-step-guide\/","title":{"rendered":"C\u00f3mo configurar un compresor de aire: gu\u00eda paso a paso"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"12178\" class=\"elementor elementor-12178\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f220721 e-flex e-con-boxed e-con e-parent\" data-id=\"f220721\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf8dee2 elementor-widget elementor-widget-heading\" data-id=\"bf8dee2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><b>C\u00f3mo configurar un compresor de aire: gu\u00eda paso a paso<\/b><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-084ba80 elementor-widget elementor-widget-text-editor\" data-id=\"084ba80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfNecesita ayuda para configurar su compresor de aire? No busque m\u00e1s: este detallado diagrama incluye instrucciones paso a paso y consejos \u00fatiles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b73ff0a elementor-widget elementor-widget-image\" data-id=\"b73ff0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/nxcompressor.com\/wp-content\/uploads\/2025\/11\/\u6da1\u65cb\u673a-\u7d2b\u8272-4jpg.webp\" class=\"attachment-large size-large wp-image-20395\" alt=\"Compresores Scroll sin aceite\" srcset=\"https:\/\/nxcompressor.com\/wp-content\/uploads\/2025\/11\/\u6da1\u65cb\u673a-\u7d2b\u8272-4jpg.webp 1000w, https:\/\/nxcompressor.com\/wp-content\/uploads\/2025\/11\/\u6da1\u65cb\u673a-\u7d2b\u8272-4jpg-300x300.webp 300w, https:\/\/nxcompressor.com\/wp-content\/uploads\/2025\/11\/\u6da1\u65cb\u673a-\u7d2b\u8272-4jpg-150x150.webp 150w, https:\/\/nxcompressor.com\/wp-content\/uploads\/2025\/11\/\u6da1\u65cb\u673a-\u7d2b\u8272-4jpg-768x768.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2be8ad6 e-flex e-con-boxed e-con e-child\" data-id=\"2be8ad6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec3c7e elementor-widget elementor-widget-heading\" data-id=\"4ec3c7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Instalar compresor de aire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-730e1c2 elementor-widget elementor-widget-text-editor\" data-id=\"730e1c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>A la hora de instalar un compresor secador de aire, es importante elegir un lugar espacioso y bien iluminado para facilitar el funcionamiento y el mantenimiento.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>El entorno debe tener una humedad relativa baja, un polvo m\u00ednimo y una buena ventilaci\u00f3n para garantizar una salida de aire limpio y seco.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>La temperatura del entorno debe mantenerse por debajo de 40\u2103, ya que las temperaturas m\u00e1s altas pueden reducir la cantidad de salida de aire.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Si el entorno de la f\u00e1brica es deficiente con altos niveles de polvo, se recomienda instalar un dispositivo de prefiltrado.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Tambi\u00e9n es aconsejable reservar espacio para el mantenimiento y facilitar el acceso de equipos de mantenimiento, como una gr\u00faa.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>El compresor de aire debe estar a una distancia m\u00ednima de 70 cm de la pared, y la distancia entre el compresor y el techo debe ser de al menos 1 metro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab46627 e-flex e-con-boxed e-con e-child\" data-id=\"ab46627\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99fe1da elementor-widget elementor-widget-heading\" data-id=\"99fe1da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Asuntos que requieren atenci\u00f3n en las tuber\u00edas, los cimientos y el sistema de refrigeraci\u00f3n del compresor de aire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96a7634 elementor-widget elementor-widget-text-editor\" data-id=\"96a7634\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 18pt;\"><strong><b>\u25cf Precauciones con las tuber\u00edas para las l\u00edneas de aire.<\/b><\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73f34e7 elementor-widget elementor-widget-text-editor\" data-id=\"73f34e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>En primer lugar, las tuber\u00edas deben tener una inclinaci\u00f3n de 1\u00b0-2\u00b0 para permitir un drenaje adecuado de la condensaci\u00f3n.<\/li><li>En segundo lugar, la ca\u00edda de presi\u00f3n en las tuber\u00edas no debe superar el 5% de la presi\u00f3n de ajuste del compresor, por lo que es mejor utilizar tuber\u00edas de mayor di\u00e1metro.<\/li><li>En tercer lugar, las derivaciones deben tomarse de la parte superior de la l\u00ednea principal para evitar que la condensaci\u00f3n fluya hacia el equipo.<\/li><li>En cuarto lugar, si se instalan varios compresores en serie, debe a\u00f1adirse una v\u00e1lvula de bola o una v\u00e1lvula de drenaje autom\u00e1tica al final de la l\u00ednea principal para facilitar el drenaje de la condensaci\u00f3n.<\/li><li>En quinto lugar, no debe reducirse arbitrariamente el tama\u00f1o de la l\u00ednea principal y, si es necesario, debe utilizarse un reductor c\u00f3nico para evitar la mezcla y la p\u00e9rdida de presi\u00f3n en las juntas.<\/li><li>En sexto lugar, si el compresor tiene un tanque de almacenamiento y un secador, la configuraci\u00f3n ideal de las tuber\u00edas es compresor de tornillo + tanque de almacenamiento + prefiltro + secador + postfiltro + filtro de precisi\u00f3n. Esta configuraci\u00f3n puede filtrar parte de la condensaci\u00f3n del tanque de almacenamiento y reducir la carga del secador o del filtro.<\/li><li>En s\u00e9ptimo lugar, si el uso de aire es grande e instant\u00e1neo, debe a\u00f1adirse un tanque de almacenamiento como amortiguador (con una capacidad mayor o igual a 20% del volumen m\u00e1ximo de aire instant\u00e1neo) para reducir la frecuencia de carga y descarga del compresor y las acciones de los componentes de control.<\/li><li>En octavo lugar, para el aire comprimido con una presi\u00f3n del sistema inferior a 1,5 MPa, la velocidad del caudal en la tuber\u00eda de impulsi\u00f3n debe ser inferior a 15 m\/s para evitar una ca\u00edda de presi\u00f3n excesiva.<\/li><li>En noveno lugar, se debe minimizar el uso de codos y v\u00e1lvulas en las tuber\u00edas para reducir la p\u00e9rdida de presi\u00f3n.<\/li><li>En d\u00e9cimo lugar, la configuraci\u00f3n ideal de las tuber\u00edas es que la l\u00ednea principal rodee toda la planta, de modo que se pueda obtener aire comprimido desde cualquier lugar. Deben instalarse v\u00e1lvulas adecuadas en la l\u00ednea principal circular para fines de mantenimiento y parada.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44ba3a2 elementor-widget elementor-widget-text-editor\" data-id=\"44ba3a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><strong><b>B\u00e1sico<\/b><\/strong><\/span><strong><b><br \/><\/b><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5350cfd elementor-widget elementor-widget-text-editor\" data-id=\"5350cfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>La cimentaci\u00f3n debe construirse sobre un suelo duro, y el plano de cimentaci\u00f3n debe nivelarse antes de la instalaci\u00f3n para evitar el ruido causado por la vibraci\u00f3n del compresor de aire.<\/li><li>Si el compresor de aire est\u00e1 instalado en el piso superior, debe realizarse un tratamiento antivibraciones para evitar que las vibraciones se transmitan al piso inferior o provoquen resonancias, lo que supondr\u00eda un peligro para la seguridad del compresor de aire y del propio edificio.<\/li><li>La vibraci\u00f3n generada por el compresor de aire de tornillo es muy peque\u00f1a, por lo que no es necesaria una cimentaci\u00f3n fija. Pero el terreno donde se coloque debe ser plano, y el suelo no puede ser blando. Lo mejor es cubrir la parte inferior del compresor de aire con cojines o almohadillas antivibraci\u00f3n para evitar las vibraciones y el ruido.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5ba448 elementor-widget elementor-widget-text-editor\" data-id=\"f5ba448\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><strong><b>Sistema de refrigeraci\u00f3n<\/b><\/strong><\/span><b><\/b><b><\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19976c9 elementor-widget elementor-widget-text-editor\" data-id=\"19976c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Al seleccionar un compresor de aire refrigerado por aire, debe tenerse en cuenta el entorno de ventilaci\u00f3n. No coloque el compresor de aire cerca de equipos de alta temperatura para evitar que el compresor de aire aspire atm\u00f3sfera de alta temperatura y provoque que la temperatura de escape sea demasiado alta y afecte al funcionamiento normal de la unidad.<\/li><li>Cuando las condiciones de uso limitan la instalaci\u00f3n del compresor de aire en un espacio reducido, debe estar equipado con un equipo de succi\u00f3n y escape para facilitar la circulaci\u00f3n del aire, y la capacidad del equipo de succi\u00f3n y escape debe ser mayor que la del ventilador de refrigeraci\u00f3n del compresor de aire El volumen de aire de escape, y la posici\u00f3n de la entrada de aire de escape debe ser adecuada para la posici\u00f3n de la salida de aire de escape caliente del compresor de aire.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f01364f elementor-widget elementor-widget-heading\" data-id=\"f01364f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Depurar y ejecutar<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ca2f1a elementor-widget elementor-widget-text-editor\" data-id=\"8ca2f1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Al poner en marcha un nuevo compresor de aire secador de aire, es importante de la empresa realizar la configuraci\u00f3n.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Antes de poner en marcha la m\u00e1quina, aseg\u00farese de que no haya personal en el interior y compruebe que no haya restos de objetos o herramientas; a continuaci\u00f3n, cierre la puerta de la unidad.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Al realizar una marcha de prueba, inspeccione cuidadosamente el sentido de giro del compresor de aire. Si se detecta que gira en sentido incorrecto, apague inmediatamente la m\u00e1quina, corte la corriente, conmute dos de las l\u00edneas trif\u00e1sicas cualesquiera y vuelva a arrancar.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Si no lo hace, puede da\u00f1ar el compresor de aire (\u00a1aseg\u00farese de prestar atenci\u00f3n a esto durante las inspecciones de potencia en f\u00e1brica!).<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>El compresor de aire no debe funcionar a presiones superiores a las especificadas en la placa de caracter\u00edsticas, ya que esto puede hacer que el motor se sobrecargue y se queme.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Cuando el compresor de aire est\u00e1 en modo de control remoto, puede ponerse en marcha en cualquier momento, as\u00ed que aseg\u00farese de colocar una se\u00f1al de advertencia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ccb846b e-flex e-con-boxed e-con e-child\" data-id=\"ccb846b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94d484b elementor-widget elementor-widget-heading\" data-id=\"94d484b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mantenimiento y reparaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6101721 elementor-widget elementor-widget-text-editor\" data-id=\"6101721\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El mantenimiento y la reparaci\u00f3n del compresor de aire deben realizarse bajo la supervisi\u00f3n de personal cualificado.<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>El aire comprimido y los aparatos el\u00e9ctricos son peligrosos. Durante la inspecci\u00f3n o el mantenimiento, es necesario confirmar que se ha cortado la alimentaci\u00f3n el\u00e9ctrica y colgar se\u00f1ales de advertencia como \u201cinspecci\u00f3n\u201d o \u201cprohibido abrir\u201d en la alimentaci\u00f3n el\u00e9ctrica para evitar lesiones causadas por otras personas que conecten y transmitan electricidad;<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>En caso de parada por mantenimiento, es necesario esperar a que todo el compresor de aire se enfr\u00ede y el aire comprimido del sistema se libere de forma segura, y el personal de mantenimiento debe intentar evitar cualquier puerto de escape del sistema del compresor de aire y cerrar la v\u00e1lvula de aislamiento correspondiente;<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Al limpiar las piezas de la unidad, deben utilizarse disolventes no corrosivos y seguros, y est\u00e1 terminantemente prohibido el uso de productos de limpieza inflamables, explosivos y vol\u00e1tiles;<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Despu\u00e9s de que el compresor de aire haya estado funcionando durante un periodo de tiempo, la v\u00e1lvula de seguridad y otros sistemas de protecci\u00f3n deben inspeccionarse peri\u00f3dicamente para garantizar su sensibilidad y fiabilidad, normalmente una vez al a\u00f1o;<\/p><p><span style=\"font-size: 18pt;\"><strong><b>\u25cf <\/b><\/strong><\/span>Las piezas de repuesto del compresor de aire deben ser suministradas por la f\u00e1brica original, y el aceite del tornillo debe ser el aceite especial designado por la empresa para el compresor de aire de tornillo, y est\u00e1 estrictamente prohibido mezclar las dos marcas de aceite, de lo contrario causar\u00e1 coquizaci\u00f3n en el sistema y provocar\u00e1 accidentes mayores.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfNecesita ayuda para configurar su compresor de aire? No busque m\u00e1s: este detallado diagrama incluye instrucciones paso a paso y consejos \u00fatiles.<\/p>","protected":false},"author":2,"featured_media":20013,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[40],"tags":[87,88,75],"class_list":["post-12178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compressor-academy","tag-aircompressordiagram","tag-aircompressorsetup","tag-diyaircompressor"],"acf":[],"_links":{"self":[{"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/posts\/12178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/comments?post=12178"}],"version-history":[{"count":4,"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/posts\/12178\/revisions"}],"predecessor-version":[{"id":21806,"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/posts\/12178\/revisions\/21806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/media\/20013"}],"wp:attachment":[{"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/media?parent=12178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/categories?post=12178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nxcompressor.com\/es\/wp-json\/wp\/v2\/tags?post=12178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}